{"id":18521,"date":"2026-06-26T15:00:29","date_gmt":"2026-06-26T15:00:29","guid":{"rendered":"https:\/\/rosedz.com\/product\/mousse-nettoyante-a-lampoule-centella-madagascar-skin1004\/"},"modified":"2026-08-12T17:08:19","modified_gmt":"2026-08-12T17:08:19","slug":"mousse-nettoyante-a-lampoule-centella-madagascar-skin1004","status":"publish","type":"product","link":"https:\/\/rosedz.com\/en\/product\/mousse-nettoyante-a-lampoule-centella-madagascar-skin1004\/","title":{"rendered":"SKIN1004 Madagascar Centella Ampoule Foam Face Cleanser"},"content":{"rendered":"<p>Un nettoyant au pH 5 avec des principes actifs d\u00e9riv\u00e9s de la noix de coco et de l&rsquo;acide citrique qui nettoie en douceur sans dess\u00e9cher ni tirailler la peau.<strong>Product benefits:<\/strong>Soothing, moisturizing, light exfoliating<strong>Type of skin:<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Un nettoyant au pH 5 avec des principes actifs d\u00e9riv\u00e9s de la noix de coco et de l&rsquo;acide citrique qui nettoie en douceur sans dess\u00e9cher ni tirailler la peau.Avantages du produit :Apaisant, hydratant, l\u00e9g\u00e8rement exfoliantType de peau :<\/p>","protected":false},"featured_media":18516,"template":"","meta":{"_veltro_stock_type":"","_veltro_stock_type_locked":"","_veltro_stock_type_source":"","_veltro_stock_type_set_at":"","_members_access_role":[],"_members_access_error":""},"pwb-brand":[847],"product_brand":[],"product_cat":[93],"product_tag":[242,225,223,270],"class_list":["post-18521","product","type-product","status-publish","has-post-thumbnail","pwb-brand-skin1004","product_cat-face-wash","product_tag-cleansing","product_tag-normalskin","product_tag-sensitive","product_tag-korean-product-2","first","outofstock","shipping-taxable","product-type-variable","has-default-attributes","wvs-archive-product-wrapper"],"brands":[{"id":847,"name":"SKIN1004","slug":"skin1004"}],"_links":{"self":[{"href":"https:\/\/rosedz.com\/en\/wp-json\/wp\/v2\/product\/18521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rosedz.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rosedz.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rosedz.com\/en\/wp-json\/wp\/v2\/media\/18516"}],"wp:attachment":[{"href":"https:\/\/rosedz.com\/en\/wp-json\/wp\/v2\/media?parent=18521"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/rosedz.com\/en\/wp-json\/wp\/v2\/pwb-brand?post=18521"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/rosedz.com\/en\/wp-json\/wp\/v2\/product_brand?post=18521"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rosedz.com\/en\/wp-json\/wp\/v2\/product_cat?post=18521"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rosedz.com\/en\/wp-json\/wp\/v2\/product_tag?post=18521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}